{"id":53,"count":2,"description":"","link":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/","name":"Tayaimgut","slug":"tayaimgut","taxonomy":"client","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tayaimgut Archives - Lateral Branding<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tayaimgut Archives - Lateral Branding\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/\" \/>\n<meta property=\"og:site_name\" content=\"Lateral Branding\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/\",\"url\":\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/\",\"name\":\"Tayaimgut Archives - Lateral Branding\",\"isPartOf\":{\"@id\":\"http:\/\/lateralbranding.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lateralbranding.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tayaimgut\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/lateralbranding.com\/en\/#website\",\"url\":\"http:\/\/lateralbranding.com\/en\/\",\"name\":\"Lateral Branding\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/lateralbranding.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/lateralbranding.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/lateralbranding.com\/en\/#organization\",\"name\":\"Lateral Branding\",\"url\":\"http:\/\/lateralbranding.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/lateralbranding.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lateralbranding.com\/wp-content\/uploads\/logo-lateralbranding.png\",\"contentUrl\":\"https:\/\/lateralbranding.com\/wp-content\/uploads\/logo-lateralbranding.png\",\"width\":400,\"height\":60,\"caption\":\"Lateral Branding\"},\"image\":{\"@id\":\"http:\/\/lateralbranding.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tayaimgut Archives - Lateral Branding","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/","og_locale":"en_US","og_type":"article","og_title":"Tayaimgut Archives - Lateral Branding","og_url":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/","og_site_name":"Lateral Branding","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/","url":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/","name":"Tayaimgut Archives - Lateral Branding","isPartOf":{"@id":"http:\/\/lateralbranding.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lateralbranding.com\/en\/cliente\/tayaimgut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lateralbranding.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tayaimgut"}]},{"@type":"WebSite","@id":"http:\/\/lateralbranding.com\/en\/#website","url":"http:\/\/lateralbranding.com\/en\/","name":"Lateral Branding","description":"","publisher":{"@id":"http:\/\/lateralbranding.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/lateralbranding.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/lateralbranding.com\/en\/#organization","name":"Lateral Branding","url":"http:\/\/lateralbranding.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/lateralbranding.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lateralbranding.com\/wp-content\/uploads\/logo-lateralbranding.png","contentUrl":"https:\/\/lateralbranding.com\/wp-content\/uploads\/logo-lateralbranding.png","width":400,"height":60,"caption":"Lateral Branding"},"image":{"@id":"http:\/\/lateralbranding.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lateralbranding.com\/en\/wp-json\/wp\/v2\/client\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lateralbranding.com\/en\/wp-json\/wp\/v2\/client"}],"about":[{"href":"https:\/\/lateralbranding.com\/en\/wp-json\/wp\/v2\/taxonomies\/client"}],"wp:post_type":[{"href":"https:\/\/lateralbranding.com\/en\/wp-json\/wp\/v2\/projects?client=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}